{"id":262,"date":"2025-12-26T15:43:05","date_gmt":"2025-12-26T14:43:05","guid":{"rendered":"https:\/\/lhoteldeverre.noosfere.org\/?p=262"},"modified":"2025-12-26T15:44:52","modified_gmt":"2025-12-26T14:44:52","slug":"top-12-lecture-2025","status":"publish","type":"post","link":"https:\/\/lhoteldeverre.noosfere.org\/index.php\/2025\/12\/26\/top-12-lecture-2025\/","title":{"rendered":"Top 12 lecture 2025"},"content":{"rendered":"\n<p>Un peu plus d&rsquo;une centaine de livres lus, moins d&rsquo;une dizaine en VO, et un constat clair : ce n&rsquo;est pas une bonne ann\u00e9e pour la science-fiction dont les titres qui m&rsquo;ont marqu\u00e9 doivent se compter sur les doigts d&rsquo;une main. En cons\u00e9quence c&rsquo;est une s\u00e9lection beaucoup plus \u00e9clectique. Je vous donne \u00e7a dans l&rsquo;ordre alphab\u00e9tique.<br><br><strong><a href=\"https:\/\/www.noosfere.org\/livres\/niourf.asp?numlivre=2146642092\">Les bons voisins<\/a>, Nina Allan<\/strong><br>J&rsquo;avais lu ce livre en VO \u00e0 sa sortie en 2021, mais l&rsquo;\u00e9criture de Nina allan est tellement riche que je l&rsquo;ai relu en VF cettte ann\u00e9e. Ce n&rsquo;est pas mon livre pr\u00e9f\u00e9r\u00e9 de l&rsquo;autrice (le cr\u00e9ateur de poup\u00e9es est pour moi son chef-d\u2019\u0153uvre) mais cette histoire myst\u00e9rieuse de meurtre familial est malgr\u00e9 tout une grande r\u00e9ussite, et le livre m\u00e9rite amplement le succ\u00e8s et les \u00e9loges qu&rsquo;il re\u00e7oit depuis sa parution chez les excellentes \u00e9ditions Tristram.<\/p>\n\n\n\n<p><strong>Aatea, Anouck Faure<\/strong><br>Un monde aquatique, des \u00eeles vivantes, des pirates : on plonge vite dans ce roman d&rsquo;aventures aux cot\u00e9s d&rsquo;Aatea et de son bateau, on se laisse emporter par les courant d&rsquo;un bout \u00e0 l&rsquo;autre, on est \u00e9merveill\u00e9 par ce nouveau monde. \u00c7a ne m&rsquo;\u00e9tonnerait pas que ce beau roman obtienne le grand prix de l&rsquo;imaginaire l&rsquo;ann\u00e9e prochaine.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/lhoteldeverre.noosfere.org\/index.php\/2025\/01\/20\/les-terres-indomptees-lauren-groff\/\">Les terres indompt\u00e9es<\/a>, Lauren Groff<\/strong><br>Lauren Groff nous livre ici, par le biais d\u2019un retour \u00e0 la nature, un sublime r\u00e9cit de lib\u00e9ration d\u2019une femme (je pique la conclusion de ma critique). Groff lutte \u00e0 sa mani\u00e8re, par ses livres et par sa librairie situ\u00e9e en Floride o\u00f9 elle vend les livres censur\u00e9es dans les biblioth\u00e8ques publiques de l&rsquo;\u00e9tat, contre la chape r\u00e9actionnaire qui s&rsquo;\u00e9tend sur les \u00c9tats-Unis. Lisez ses livres, ils sont formidables.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.noosfere.org\/livres\/niourf.asp?numlivre=2146640997\">Soeurs<\/a>, Daisy Johnson<\/strong><br>Le fantastique sombre de ce roman a \u00e9t\u00e9 adapt\u00e9 au cin\u00e9ma sous le titre<em> July &amp; September<\/em>. Deux soeurs, exil\u00e9es dans un village de bord de mer suite \u00e0 un \u00e9v\u00e9nement dramatique. Aussi bien le film que le livre sont tr\u00e8s forts, je vous laisse le choix du m\u00e9dia.<br><br><strong><a href=\"https:\/\/www.noosfere.org\/livres\/niourf.asp?numlivre=2146640708\">Incandescentes<\/a>, Hannah Kent<\/strong><br>Au milieu du 19e si\u00e8cle, des luth\u00e9riens radicaux allemands \u00e9migrent vers l&rsquo;Australie pour pouvoir pratiquer tranquillement leur religion. Un r\u00e9cit historique qui bascule d&rsquo;un coup dans le fantastique, un r\u00e9cit familial dans un territoire en cours de colonisation. <\/p>\n\n\n\n<p><strong>Yellowface, R.F. Kuang<\/strong><br>Changement radical de ton apr\u00e8s l&rsquo;excellente fantasy de Babel : Yellowface est un r\u00e9cit grin\u00e7ant sur le milieu \u00e9ditorial am\u00e9ricain. On rit beaucoup dans cette farce m\u00ealant appropriation culturelle et cynisme commercial. <\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.noosfere.org\/livres\/niourf.asp?numlivre=2146642244\">Searoad<\/a>, UK Le guin<\/strong><br>Dernier in\u00e9dit de l&rsquo;autrice am\u00e9ricaine, Searoad nous raconte, par le biais de douze nouvelles, la vie de femmes d&rsquo;une petite ville de l&rsquo;Oregon sur une p\u00e9riode de 150 ans. Ai-je besoin de vous dire que c&rsquo;est tr\u00e8s bien ?<\/p>\n\n\n\n<p><strong>Ne tirez pas sur l&rsquo;oiseau moqueur, Harper Lee<\/strong><br>Sud des \u00c9tats-Unis, ann\u00e9es trente, un homme est accus\u00e9 de viol sans preuve. Cet homme est noir, la femme est blanche, donc la justice va \u00eatre exp\u00e9ditive. C&rsquo;est racont\u00e9 par une enfant dont le p\u00e8re, avocat, va s&rsquo;occuper de la d\u00e9fense de l&rsquo;accus\u00e9, m\u00eame s&rsquo;il sait que la cause est d\u00e9sesp\u00e9r\u00e9e. Certainement le livre qui m&rsquo;a le plus touch\u00e9 cette ann\u00e9e, on ne peut qu&rsquo;\u00eatre au bord des larmes dans certains passages.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.noosfere.org\/livres\/niourf.asp?numlivre=2146642035\">Tovaangar<\/a>, C\u00e9line Minard<\/strong><br>Un post-apo joyeux dans un Los Angeles redevenu un espace naturel et vivant. De l&rsquo;\u00e9merveillement \u00e0 chaque page.<\/p>\n\n\n\n<p><strong>Le Ch\u00e2teau d&rsquo;Otrante, Howard Walpole<\/strong><br>Petite plong\u00e9e dans les \u0153uvres fondatrices du roman gothique cet \u00e9t\u00e9 : le Moine de Matthew Lewis, Les Myst\u00e8res du ch\u00e2teau d&rsquo;Udolphe d&rsquo;Ann Radcliffe et le ch\u00e2teau d&rsquo;Otrante. Des romans qui s&rsquo;ils portent tous les marques du gothique sont totalement dissemblables par ailleurs. <br>Otrante, c&rsquo;est un peu le gothique version Monty Python : de l&rsquo;absurde, du comique de situation, des personnages haut en couleur, ce roman n&rsquo;a pas pris une ride.<\/p>\n\n\n\n<p><strong>Du bout des doigts, Sarah Waters<\/strong><br>En 1862, une jeune orpheline est recrut\u00e9e par un escroc pour d\u00e9tourner la fortune d&rsquo;une jeun h\u00e9riti\u00e8re. Roman \u00e0 suspense m\u00ealant escroqueries, trahisons, \u00e9rotisme et relation lesbienne, Du bout des doigts est le genre de livre qui vous happe et qu&rsquo;on lit d&rsquo;une traite ou presque (750 pages en poche quand m\u00eame). Il a \u00e9t\u00e9 brillamment adapt\u00e9 au cin\u00e9ma par un r\u00e9alisateur cor\u00e9en qui l&rsquo;a relocalis\u00e9, mais si je vous dis le titre cela risque de vous spoiler la lecture&#8230;<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.noosfere.org\/livres\/niourf.asp?numlivre=2146642213\">Vers ma fin<\/a>, Sophie White<\/strong><br>Un roman d&rsquo;horreur psychologique avec des relations familiales \u00e9tranges sur une petite \u00eele. Premier titre de la nouvelle collection d&rsquo;horreur Styx, c&rsquo;est une lecture \u00e2pre remplie de sc\u00e8nes marquantes. <\/p>\n\n\n\n<p><br><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un peu plus d&rsquo;une centaine de livres lus, moins d&rsquo;une dizaine en VO, et un constat clair : ce n&rsquo;est pas une bonne ann\u00e9e pour la science-fiction dont les titres qui m&rsquo;ont marqu\u00e9 doivent se compter sur les doigts d&rsquo;une &hellip; <a href=\"https:\/\/lhoteldeverre.noosfere.org\/index.php\/2025\/12\/26\/top-12-lecture-2025\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-262","post","type-post","status-publish","format-standard","hentry","category-litterature"],"_links":{"self":[{"href":"https:\/\/lhoteldeverre.noosfere.org\/index.php\/wp-json\/wp\/v2\/posts\/262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lhoteldeverre.noosfere.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lhoteldeverre.noosfere.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lhoteldeverre.noosfere.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lhoteldeverre.noosfere.org\/index.php\/wp-json\/wp\/v2\/comments?post=262"}],"version-history":[{"count":4,"href":"https:\/\/lhoteldeverre.noosfere.org\/index.php\/wp-json\/wp\/v2\/posts\/262\/revisions"}],"predecessor-version":[{"id":266,"href":"https:\/\/lhoteldeverre.noosfere.org\/index.php\/wp-json\/wp\/v2\/posts\/262\/revisions\/266"}],"wp:attachment":[{"href":"https:\/\/lhoteldeverre.noosfere.org\/index.php\/wp-json\/wp\/v2\/media?parent=262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lhoteldeverre.noosfere.org\/index.php\/wp-json\/wp\/v2\/categories?post=262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lhoteldeverre.noosfere.org\/index.php\/wp-json\/wp\/v2\/tags?post=262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}